{"id":11107,"date":"2023-02-09T10:18:28","date_gmt":"2023-02-09T09:18:28","guid":{"rendered":"https:\/\/www.n-town.de\/glubbblog\/?p=11107"},"modified":"2023-02-09T12:37:57","modified_gmt":"2023-02-09T11:37:57","slug":"dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden","status":"publish","type":"post","link":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html","title":{"rendered":"DFB-Pokal: FCN &#8211; F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden!"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg\" class=\"alignleft size-medium wp-image-11105\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg 500w, https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>JAAA! Der Glubb kann ja doch noch siegen! Was f\u00fcr ein Zitterspiel, aber wir sind eine Runde weiter! Der 1.FC N\u00fcrnberg besiegt die Fortuna aus D\u00fcsseldorf im Pokal-Achtelfinale mit 5:3 im Elfmeterschie\u00dfen. Nach regul\u00e4rer Spielzeit hatte es 1:1 gestanden. Das war heute extrem wichtig: F\u00fcr Stimmung und Selbstvertrauen in der Truppe vor dem wichtigen Regensburg-Spiel &#8211; und nat\u00fcrlich aus finanzieller Sicht. Eine Summe von 2 Millionen Euro steht im Raum. Ketzerische Zungen behaupten gar, dass es heute wichtiger war, als das <a href=\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11086-fuerth-fcn-10-wir-verlieren-das-scheiss-00-in-der-nachspielzeit.html\" target=\"_blank\" rel=\"noopener\">Frankenderby<\/a> zu gewinnen. Denke aber nicht, dass das jeder Glubberer so sieht. Egal! Heute k\u00f6nnen wir mal wieder stolz auf unseren Glubb sein!<\/p>\n<p>Der FCN dr\u00fcckt gleich, kommt sogar zu M\u00f6glichkeiten: Tempelmann nach toller Kombination an die Latte und Duah \u00fcber das Tor. Als D\u00fcsseldorf dann einmal vors Tor kommt, schepperts. Ijoha hat viel Platz, Valentini greift nicht an, sodass er flanken kann und in der Mitte Kownacki einnickt. 0:1. Keine Chance f\u00fcr Vindahl. Alles wie gewohnt.<\/p>\n<p>Nach der Pause rennt der Glubb an, ohne irgendwie zwingend zu werden. Dickste Chance von Daferner per Kopf, aber Kastenmeier kann noch retten. Dann die Fortuna mit mega Chancen: Tanaka aus wenigen Metern \u00fcber das Tor. Nach einem Konter kann Vindahl im eins gegen eins retten.<\/p>\n<p>Dann wird Taylan Duman eingewechselt! Pl\u00f6tzlich mehr Zug im N\u00fcrnberger Spiel. Doch die Nachspielzeit l\u00e4uft schon.<\/p>\n<p>Als sich D\u00fcsseldorf aufs Zeitspiel konzentriert, kommt Mats M\u00f6ller-Daehli \u00fcber links, passt in die Mitte&#8230;. Lohkemper haut einen Schwinger, aber hinter ihm kommt Duman zum Schuss und schlenzt den Ball ins lange Eck! TOOOR! Ausgleich! 1:1! Riesenjubel!<\/p>\n<p>Dass der Ball abgef\u00e4lscht war, ist uninteressant. Jetzt gibt es Verl\u00e4ngerung!<\/p>\n<p>Sofort ist D\u00fcsseldorf hellwach! Hendrix alleine von Vindahl, lupft den Ball \u00fcber den Schlussmann, der Ball h\u00fcpft aufs leere Tor zu, da kommt Flick hinterher gesprintet und rettet vor der Linie! Wahnsinn!<\/p>\n<p>Kurz vor dem Seitenwechsel klatscht ein D\u00fcsseldorfer Freisto\u00df ans Lattenkreuz und auch sp\u00e4ter h\u00e4lt uns Vindahl im Spiel.<\/p>\n<p>Dann die 120. Minute: Niemic wird steil geschickt und l\u00e4uft alleine auf Vindahl zu. Flick sprintet wieder hinterher und zieht die Notbremse. Glatt rot f\u00fcr den jungen Schalker. Er hat sich f\u00fcr das Team geopfert!<\/p>\n<p>Elfmeterschie\u00dfen:<\/p>\n<p>Geis ist der erste Sch\u00fctze und verwandelt sicher. Kastenmeier macht bei Fortuna den ersten Sch\u00fctzen und verwandelt ebenso sicher.<\/p>\n<p>Dann l\u00e4uft Duman an und Kastenmeier h\u00e4lt! Doch das Schiedsrichterteam reagiert sofort: Kastenmeier hat sich von der Linie wegbewegt. Elfmeter muss wiederholt werden: Duman darf noch mal und verwandelt sicher in die andere Ecke. 2:1.<\/p>\n<p>Nach dem Ausgleich f\u00fcr D\u00fcsseldorf l\u00e4uft Gyamerah und setzt den Ball eiskalt und sicher neben den Pfosten! 3:2!<\/p>\n<p>Wieder Ausgleich und Schindler l\u00e4uft an. Nicht wenige erinnern sich an <a href=\"https:\/\/youtu.be\/a2kQeumEY4Q\" target=\"_blank\" rel=\"noopener\">Schindlers 300-Mio-Elfer f\u00fcr Huddersfield<\/a>. Er zielt genau ins Eck, Kastenmeier ist dran, aber den Ball geht ins Netz! Ja! 4:3!<\/p>\n<p>Nun ist Niemiec dran. Er zieht aufs linke Eck, wo Vindahl hinhechtet und H\u00c4LT!! Jaaaa!<\/p>\n<p>Nun hat Shuranov den Sieg auf dem Fu\u00df. Er l\u00e4uft an, verz\u00f6gert kurz und knallt ihn ins linke Eck! AUS! JAAAA! Wir sind weiter!!<\/p>\n<p><strong>Fazit<\/strong>:<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5540.jpg\" class=\"alignleft size-medium wp-image-11106\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5540.jpg 500w, https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5540-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Endlich! Endlich mal wieder ausgelassener Jubel im Max-Morlock-Stadion! Ich hatte schon nicht mehr dran gedacht! F\u00fcr mich Mann des Spiels und Pokalheld, der leider etwas im Hintergrund steht ist Florian Flick. Er war ein absoluter Aktivposten im N\u00fcrnberger Spiel, er rettete auf der Linie und opferte sich schlie\u00dflich, damit es ins Elfmeterschie\u00dfen gehen kann! Toller Junge!<\/p>\n<p>Bei all dem Jubel m\u00fcssen wir nat\u00fcrlich auch im Kopf behalten, dass es \u00fcber weite Strecken wieder sehr z\u00e4h war, was der FCN geboten hat. Angefangen von Valentini, der beim Gegentor nicht rausr\u00fcckt &#8211; sogar Weinzierl ruft das von drau\u00dfen rein &#8211; bis zu einen fast unsichtbaren Kwadwo Duah. Daf\u00fcr bin ich froh, dass Taylan Duman wieder zur\u00fcck ist, an ihn dachte ich als ich nach dem <a href=\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11086-fuerth-fcn-10-wir-verlieren-das-scheiss-00-in-der-nachspielzeit.html\" target=\"_blank\" rel=\"noopener\">F\u00fcrth-Spiel von der R\u00fcckkehr von verletzten Spielern<\/a> schrieb. <a href=\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/10384-dfb-pokal-ulm-fcn-01-kleiner-duman-ganz-gross.html\" target=\"_blank\" rel=\"noopener\">Taylan ist einfach der Pokalheld<\/a> in N\u00fcrnberg!<\/p>\n<p>Statistik: Tore 1:1, Torsch\u00fcsse 17:15 Ballbesitz 53:47%, Zweikampfquote 45:55%, Ecken 5:6. Es zeigt sehr sch\u00f6n, wie stark die Fortuna heute war. An der Zweikampfquote muss gearbeitet werden!<\/p>\n<p>Nun ist der Glubb der letzte verbliebene Zweitligist im DFB-Pokal und steht im erlauchten Kreis neben Stuttgart, Union Berlin, RB Leipzig, Bayern, Freiburg, Frankfurt und Borussia Dortmund. Mal sehen, was die Auslosung am 19.02.23 ab 17:10 Uhr im ZDF ergibt. Nicht wenige denken ja, dass wir nach M\u00fcnchen zu den Bayern m\u00fcssen &#8211; das w\u00e4re wiedermal typisch.<\/p>\n<p><strong>Fans:<\/strong><\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5541.jpg\" class=\"alignleft wp-image-11112\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5541.jpg 500w, https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5541-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Also 26.000 Zuschauer waren schon entt\u00e4uschend, aber in Anbetracht der letzten Leistungen und der Minusgrade auch absolut verst\u00e4ndlich. Wahrscheinlich hatten die Verantwortlichen sogar mit noch weniger gerechnet, wie sonst in das Chaos bei den Eing\u00e4ngen zu verstehen. Denn das Bild hier links wurde 4 Minuten vor Spielbeginn aufgenommen. Tja, unter der Woche schaffen es nicht alle fr\u00fchzeitig aus der Arbeit raus. Als das Gedr\u00e4nge zu gro\u00df zu werden drohte, entschlossen sich die Verantwortlichen zur \u00d6ffnung der Drehkreuze. So dass keiner mehr die Karten zeigen musste. F\u00fcr mich in dem Fall die richtige Entscheidung.<\/p>\n<p>Respektabel f\u00fcr mich aber die Menge an G\u00e4stefans, die also hier wirklich \u00fcber einen Block f\u00fcllten und auch lautstark unterwegs waren.<\/p>\n<p>Schade fand ich, dass die Truppe einen Jubellauf in die Kurve hinlegte, aber die Ultras offensichtlich nicht mit ihnen feiern wollten. Das &#8220;<a href=\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/allgemein\/39-erste-runde-bukarest-zweite-runde-rom-in-kopenhagen-schellt-das-telefon.html\" target=\"_blank\" rel=\"noopener\">Europapokaaal<\/a>&#8221; kam aus dem 11er. Ich vermute mal eine &#8220;kalte Schulter&#8221; nach der <a href=\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11086-fuerth-fcn-10-wir-verlieren-das-scheiss-00-in-der-nachspielzeit.html\" target=\"_blank\" rel=\"noopener\">Derbyniederlage<\/a>.<\/p>\n<p>Aber jetzt m\u00fcssen wir alle zusammenhalten um am kommenden Samstag den Jahn aus Regensburg aus dem Stadion zu schie\u00dfen! Denn bei all dem Jubel heute: Wir sind immer noch 16. der 2. Bundesliga! Gebt alles. M\u00e4nner, ein Sieg muss her! Dann feiern auch die Ultras mit Euch!<\/p>\n<p>Alles f\u00fcr rot-schwarz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JAAA! Der Glubb kann ja doch noch siegen! Was f\u00fcr ein Zitterspiel, aber wir sind eine Runde weiter! Der 1.FC N\u00fcrnberg besiegt die Fortuna aus D\u00fcsseldorf im Pokal-Achtelfinale mit 5:3 im Elfmeterschie\u00dfen. Nach regul\u00e4rer Spielzeit hatte es 1:1 gestanden. Das war heute extrem wichtig: F\u00fcr Stimmung und Selbstvertrauen in der Truppe vor dem wichtigen Regensburg-Spiel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[5],"tags":[83,345],"jetpack_featured_media_url":"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DFB-Pokal: FCN - F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden! - Glubb-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DFB-Pokal: FCN - F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden! - Glubb-Blog\" \/>\n<meta property=\"og:description\" content=\"JAAA! Der Glubb kann ja doch noch siegen! Was f\u00fcr ein Zitterspiel, aber wir sind eine Runde weiter! Der 1.FC N\u00fcrnberg besiegt die Fortuna aus D\u00fcsseldorf im Pokal-Achtelfinale mit 5:3 im Elfmeterschie\u00dfen. Nach regul\u00e4rer Spielzeit hatte es 1:1 gestanden. Das war heute extrem wichtig: F\u00fcr Stimmung und Selbstvertrauen in der Truppe vor dem wichtigen Regensburg-Spiel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html\" \/>\n<meta property=\"og:site_name\" content=\"Glubb-Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/glubbblog\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-09T09:18:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-09T11:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@glubb_blog_de\" \/>\n<meta name=\"twitter:site\" content=\"@glubb_blog_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bomber Manolo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/#website\",\"url\":\"https:\/\/www.n-town.de\/glubbblog\/\",\"name\":\"Glubb-Blog\",\"description\":\"Clubfans bei FCN-Ausw\u00e4rtsfahrten und Groundhopping\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.n-town.de\/glubbblog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg\",\"contentUrl\":\"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg\",\"width\":500,\"height\":375},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#webpage\",\"url\":\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html\",\"name\":\"DFB-Pokal: FCN - F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden! - Glubb-Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#primaryimage\"},\"datePublished\":\"2023-02-09T09:18:28+00:00\",\"dateModified\":\"2023-02-09T11:37:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/#\/schema\/person\/23822a94b519ca1de591c4492e0e104e\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.n-town.de\/glubbblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DFB-Pokal: FCN &#8211; F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/#\/schema\/person\/23822a94b519ca1de591c4492e0e104e\",\"name\":\"Bomber Manolo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.n-town.de\/glubbblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/745e89a5226a55ce3ed5fac4a51dced8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/745e89a5226a55ce3ed5fac4a51dced8?s=96&d=mm&r=g\",\"caption\":\"Bomber Manolo\"},\"sameAs\":[\"https:\/\/www.n-town.de\"],\"url\":\"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/author\/andy\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DFB-Pokal: FCN - F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden! - Glubb-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html","og_locale":"de_DE","og_type":"article","og_title":"DFB-Pokal: FCN - F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden! - Glubb-Blog","og_description":"JAAA! Der Glubb kann ja doch noch siegen! Was f\u00fcr ein Zitterspiel, aber wir sind eine Runde weiter! Der 1.FC N\u00fcrnberg besiegt die Fortuna aus D\u00fcsseldorf im Pokal-Achtelfinale mit 5:3 im Elfmeterschie\u00dfen. Nach regul\u00e4rer Spielzeit hatte es 1:1 gestanden. Das war heute extrem wichtig: F\u00fcr Stimmung und Selbstvertrauen in der Truppe vor dem wichtigen Regensburg-Spiel [&hellip;]","og_url":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html","og_site_name":"Glubb-Blog","article_publisher":"https:\/\/www.facebook.com\/glubbblog","article_published_time":"2023-02-09T09:18:28+00:00","article_modified_time":"2023-02-09T11:37:57+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@glubb_blog_de","twitter_site":"@glubb_blog_de","twitter_misc":{"Verfasst von":"Bomber Manolo","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.n-town.de\/glubbblog\/#website","url":"https:\/\/www.n-town.de\/glubbblog\/","name":"Glubb-Blog","description":"Clubfans bei FCN-Ausw\u00e4rtsfahrten und Groundhopping","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.n-town.de\/glubbblog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#primaryimage","inLanguage":"de","url":"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg","contentUrl":"https:\/\/www.n-town.de\/glubbblog\/wp-content\/uploads\/2023\/02\/img_5539.jpg","width":500,"height":375},{"@type":"WebPage","@id":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#webpage","url":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html","name":"DFB-Pokal: FCN - F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden! - Glubb-Blog","isPartOf":{"@id":"https:\/\/www.n-town.de\/glubbblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#primaryimage"},"datePublished":"2023-02-09T09:18:28+00:00","dateModified":"2023-02-09T11:37:57+00:00","author":{"@id":"https:\/\/www.n-town.de\/glubbblog\/#\/schema\/person\/23822a94b519ca1de591c4492e0e104e"},"breadcrumb":{"@id":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/glubb-live\/11107-dfb-pokal-fcn-f95-11-53-duman-flick-vindahl-und-shuranov-sind-die-pokal-helden.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.n-town.de\/glubbblog"},{"@type":"ListItem","position":2,"name":"DFB-Pokal: FCN &#8211; F95 1:1\/5:3! Duman, Flick, Vindahl und Shuranov sind die Pokal-Helden!"}]},{"@type":"Person","@id":"https:\/\/www.n-town.de\/glubbblog\/#\/schema\/person\/23822a94b519ca1de591c4492e0e104e","name":"Bomber Manolo","image":{"@type":"ImageObject","@id":"https:\/\/www.n-town.de\/glubbblog\/#personlogo","inLanguage":"de","url":"https:\/\/secure.gravatar.com\/avatar\/745e89a5226a55ce3ed5fac4a51dced8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/745e89a5226a55ce3ed5fac4a51dced8?s=96&d=mm&r=g","caption":"Bomber Manolo"},"sameAs":["https:\/\/www.n-town.de"],"url":"https:\/\/www.n-town.de\/glubbblog\/index.php\/archives\/author\/andy"}]}},"_links":{"self":[{"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/posts\/11107"}],"collection":[{"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/comments?post=11107"}],"version-history":[{"count":4,"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/posts\/11107\/revisions"}],"predecessor-version":[{"id":11116,"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/posts\/11107\/revisions\/11116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/media\/11105"}],"wp:attachment":[{"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/media?parent=11107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/categories?post=11107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.n-town.de\/glubbblog\/index.php\/wp-json\/wp\/v2\/tags?post=11107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}